{"id":209286,"date":"2023-05-05T10:52:29","date_gmt":"2023-05-05T15:52:29","guid":{"rendered":"https:\/\/ucm.edu.co\/intranet\/?page_id=209286"},"modified":"2023-05-05T10:52:30","modified_gmt":"2023-05-05T15:52:30","slug":"comite-de-convivencia-laboral","status":"publish","type":"page","link":"https:\/\/ucm.edu.co\/intranet\/comite-de-convivencia-laboral\/","title":{"rendered":"Comit\u00e9 de Convivencia Laboral"},"content":{"rendered":"<div id=\"contenedor_calendario contenedor_elementos_apilables\">\n\t\t<div class=\"posts_lista isotope\">\n\t\t\t\t\t\t\t\t<div class=\"nota_archivo elemento_apilable texto_azul_cuatro fondo_gris_uno enlace\" data-enlace=\"https:\/\/ucm.edu.co\/intranet\/que-funciones-tiene-el-comite-de-convivencia-laboral\/\">\n\t\t\t\t<div class=\"imagen_nota_archivo\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ucm.edu.co\/intranet\/wp-content\/uploads\/2023\/05\/Que\u0301-hacemos-300x0-c-f.png\">\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"overlap_elemento_apilable fondo_cat_comite-convivencia-laboral\"><\/div>\n\t\t\t\t<div class=\"textos_elemento_apilable\">\n\t\t\t\t\t<p class=\"texto_azul_cuatro texto_mini\">Comit\u00e9 Convivencia Laboral<\/p>\n\t\t\t\t\t<p class=\"texto_azul_cuatro texto_mini\">05 de mayo de 2023<\/p>\n\t\t\t\t\t<h3>\n\t\t\t\t\t\t<a href=\"https:\/\/ucm.edu.co\/intranet\/que-funciones-tiene-el-comite-de-convivencia-laboral\/\">\u00bfQu\u00e9 funciones tiene el Comit\u00e9 de Convivencia Laboral?<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\t<p class=\"texto_azul_tres\">Estas son las funciones que se desarrollan desde el Comit\u00e9&hellip;<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<span class=\"texto_azul_uno texto_grande texto_bold\">+<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"nota_archivo elemento_apilable texto_azul_cuatro fondo_gris_uno enlace\" data-enlace=\"https:\/\/ucm.edu.co\/intranet\/nuestros-representantes-en-el-comite-de-convivencia-laboral\/\">\n\t\t\t\t<div class=\"imagen_nota_archivo\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ucm.edu.co\/intranet\/wp-content\/uploads\/2023\/05\/Quie\u0301nes-somos-300x0-c-f.png\">\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"overlap_elemento_apilable fondo_cat_comite-convivencia-laboral\"><\/div>\n\t\t\t\t<div class=\"textos_elemento_apilable\">\n\t\t\t\t\t<p class=\"texto_azul_cuatro texto_mini\">Comit\u00e9 Convivencia Laboral<\/p>\n\t\t\t\t\t<p class=\"texto_azul_cuatro texto_mini\">05 de mayo de 2023<\/p>\n\t\t\t\t\t<h3>\n\t\t\t\t\t\t<a href=\"https:\/\/ucm.edu.co\/intranet\/nuestros-representantes-en-el-comite-de-convivencia-laboral\/\">Nuestros representantes en el Comit\u00e9 de Convivencia Laboral<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\t<p class=\"texto_azul_tres\">El Comit\u00e9 de Convivencia Laboral est\u00e1 compuesto por dos representantes&hellip;<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<span class=\"texto_azul_uno texto_grande texto_bold\">+<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"nota_archivo elemento_apilable texto_azul_cuatro fondo_gris_uno enlace\" data-enlace=\"https:\/\/ucm.edu.co\/intranet\/formato-para-interponer-quejas-por-posible-acoso-laboral-o-presentar-sugerencias-ante-el-comite-de-convivencia-laboral-de-la-universidad-catolica-de-manizales\/\">\n\t\t\t\t<div class=\"imagen_nota_archivo\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ucm.edu.co\/intranet\/wp-content\/uploads\/2023\/05\/Comite\u0301-de-convivencia-laboral_formato-300x0-c-f.png\">\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"overlap_elemento_apilable fondo_cat_comite-convivencia-laboral\"><\/div>\n\t\t\t\t<div class=\"textos_elemento_apilable\">\n\t\t\t\t\t<p class=\"texto_azul_cuatro texto_mini\">Comit\u00e9 Convivencia Laboral<\/p>\n\t\t\t\t\t<p class=\"texto_azul_cuatro texto_mini\">05 de mayo de 2023<\/p>\n\t\t\t\t\t<h3>\n\t\t\t\t\t\t<a href=\"https:\/\/ucm.edu.co\/intranet\/formato-para-interponer-quejas-por-posible-acoso-laboral-o-presentar-sugerencias-ante-el-comite-de-convivencia-laboral-de-la-universidad-catolica-de-manizales\/\">Formato para interponer quejas por posible acoso laboral o presentar sugerencias ante el comit\u00e9 de convivencia laboral de la Universidad Cat\u00f3lica de Manizales<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\t<p class=\"texto_azul_tres\">[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row admin_label=&#8221;row&#8221; _builder_version=&#8221;4.16&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221;&hellip;<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<span class=\"texto_azul_uno texto_grande texto_bold\">+<\/span>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"nota_archivo elemento_apilable texto_azul_cuatro fondo_gris_uno enlace\" data-enlace=\"https:\/\/ucm.edu.co\/intranet\/protocolo-comite-de-convivencia-laboral\/\">\n\t\t\t\t<div class=\"imagen_nota_archivo\">\n\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/ucm.edu.co\/intranet\/wp-content\/uploads\/2023\/05\/Comite\u0301-de-convivencia-laboral_protocolo-1-300x0-c-f.png\">\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"overlap_elemento_apilable fondo_cat_comite-convivencia-laboral\"><\/div>\n\t\t\t\t<div class=\"textos_elemento_apilable\">\n\t\t\t\t\t<p class=\"texto_azul_cuatro texto_mini\">Comit\u00e9 Convivencia Laboral<\/p>\n\t\t\t\t\t<p class=\"texto_azul_cuatro texto_mini\">05 de mayo de 2023<\/p>\n\t\t\t\t\t<h3>\n\t\t\t\t\t\t<a href=\"https:\/\/ucm.edu.co\/intranet\/protocolo-comite-de-convivencia-laboral\/\">Protocolo Comit\u00e9 de Convivencia Laboral<\/a>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\t<p class=\"texto_azul_tres\">El siguiente documento adjunto busca estandarizar el procedimiento mediante el&hellip;<\/p>\n\t\t\t\t<\/div>\n\t\t\t\t<span class=\"texto_azul_uno texto_grande texto_bold\">+<\/span>\n\t\t\t<\/div>\n\t\t\t<\/div>\n<\/div>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":275,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"off","_et_pb_old_content":"","_et_gb_content_width":"","_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-209286","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/ucm.edu.co\/intranet\/wp-json\/wp\/v2\/pages\/209286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ucm.edu.co\/intranet\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ucm.edu.co\/intranet\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ucm.edu.co\/intranet\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/ucm.edu.co\/intranet\/wp-json\/wp\/v2\/comments?post=209286"}],"version-history":[{"count":1,"href":"https:\/\/ucm.edu.co\/intranet\/wp-json\/wp\/v2\/pages\/209286\/revisions"}],"predecessor-version":[{"id":209287,"href":"https:\/\/ucm.edu.co\/intranet\/wp-json\/wp\/v2\/pages\/209286\/revisions\/209287"}],"wp:attachment":[{"href":"https:\/\/ucm.edu.co\/intranet\/wp-json\/wp\/v2\/media?parent=209286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}